{"id":1358,"date":"2025-03-21T13:57:55","date_gmt":"2025-03-21T13:57:55","guid":{"rendered":"https:\/\/cashflowch.com\/?page_id=1358"},"modified":"2025-07-15T12:40:15","modified_gmt":"2025-07-15T12:40:15","slug":"arrivee-ou-depart-de-la-suisse","status":"publish","type":"page","link":"https:\/\/cashflowch.com\/en\/arrivee-ou-depart-de-la-suisse\/","title":{"rendered":"Arriv\u00e9e ou d\u00e9part de la Suisse"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1358\" class=\"elementor elementor-1358\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50337c0e elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no\" data-id=\"50337c0e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-745c0670\" data-id=\"745c0670\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-451dcdc4 elementor-invisible\" data-id=\"451dcdc4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b4edae4 elementor-widget elementor-widget-heading\" data-id=\"3b4edae4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Arriv\u00e9e ou d\u00e9part de la Suisse<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39af145e elementor-widget elementor-widget-text-editor\" data-id=\"39af145e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conseils personnalis\u00e9s, gestion rigoureuse et solutions adapt\u00e9es pour faciliter votre arriv\u00e9e ou votre d\u00e9part de la Suisse en toute s\u00e9r\u00e9nit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98330f9 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"98330f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/calendar.notion.so\/meet\/davidecasellini\/people\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9servez un rendez-vous informatif<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-787736d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no\" data-id=\"787736d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59d087c2\" data-id=\"59d087c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70f54e13 elementor-widget elementor-widget-heading\" data-id=\"70f54e13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Arriv\u00e9e ou d\u00e9part de la Suisse\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-753069b9 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"753069b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2bd4c4 elementor-widget elementor-widget-text-editor\" data-id=\"b2bd4c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">S\u2019installer en Suisse ou quitter le pays demande bien plus que de faire ses valises. Chez <\/span><b><span data-contrast=\"auto\">Cash-Flow CH<\/span><\/b><span data-contrast=\"auto\">, nous accompagnons nos clients dans toutes les \u00e9tapes administratives, fiscales, sociales et patrimoniales pour que chaque transition se fasse <\/span><b><span data-contrast=\"auto\">en toute s\u00e9r\u00e9nit\u00e9<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><h2><span data-contrast=\"auto\">VOUS ARRIVEZ EN SUISSE ? VOICI LES \u00c9TAPES \u00c0 SUIVRE :<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/h2><div><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/div><div><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><br \/><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\"><br \/><\/span><\/div><ol><li><b><span data-contrast=\"auto\"> Annoncer votre arriv\u00e9e<\/span><\/b><\/li><\/ol><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Vous devez vous enregistrer aupr\u00e8s de la commune de domicile dans les <\/span><b><span data-contrast=\"auto\">14 jours suivant votre arriv\u00e9e<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;134233118&quot;:true,&quot;335559738&quot;:120}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"1\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Pour les ressortissants \u00e9trangers : demande de <\/span><b><span data-contrast=\"auto\">permis de s\u00e9jour<\/span><\/b><span data-contrast=\"auto\"> (L, B, C selon votre situation).<\/span><span data-ccp-props=\"{&quot;134233118&quot;:true,&quot;335559738&quot;:120}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><ol start=\"2\"><li><b><span data-contrast=\"auto\"> Assurer votre couverture sant\u00e9 (obligatoire)<\/span><\/b><\/li><\/ol><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"2\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">L\u2019assurance maladie de base (<a href=\"https:\/\/tally.so\/r\/3EXAWN\"><span style=\"text-decoration: underline;\">LAMal<\/span><\/a>) est <\/span><b><span data-contrast=\"auto\">obligatoire dans les 3 mois suivant l\u2019arriv\u00e9e<\/span><\/b><span data-contrast=\"auto\">. (si le d\u00e9lai n\u2019est pas respect\u00e9, il y a des sanctions).<\/span><span data-ccp-props=\"{&quot;134233118&quot;:true,&quot;335559738&quot;:120}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"2\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Il est possible de comparer les primes selon votre canton de domicile, compagnie d\u2019assurance, mod\u00e8le et franchise.<\/span>\u00a0<br \/><span data-contrast=\"auto\">selon la situation financi\u00e8re, il est possible de demander des aides directement au canton de domicile (<\/span><span style=\"text-decoration: underline;\"><a href=\"mailto:..\/Library\/CloudStorage\/GoogleDrive-davide.casellini@gmail.com\/Il%20mio%20Drive\/CASHFLOWCH\/PS\/LAMal\/istituzioni%20cantonali%20per%20sussidi%20LAMal.xlsx\">liste<\/a><\/span><span data-contrast=\"auto\">).<\/span>\u00a0<br \/><span data-contrast=\"auto\">\u25a1<\/span> <span data-contrast=\"auto\">Dans le cadre des Subventions de prime d\u2019assurance maladie (Remboursement individuel de prime RIP), nous tenons \u00e0 pr\u00e9ciser que nous ne faisons pas de d\u00e9marchage pour l&rsquo;octroi d\u2019aides financi\u00e8res et n&rsquo;organisons aucun rendez-vous<\/span><span data-ccp-props=\"{&quot;134233118&quot;:true,&quot;335559738&quot;:120}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"2\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"auto\">Une <\/span><span style=\"text-decoration: underline;\"><b><a href=\"https:\/\/tally.so\/r\/nGLk0p\">assurance compl\u00e9mentaire<\/a><\/b><\/span><span data-contrast=\"auto\"> peut \u00eatre utile pour une meilleure prise en charge et couvrir les frais que la couverture obligatoire ne couvre pas.<\/span>\u00a0<br \/><span data-ccp-props=\"{&quot;134233118&quot;:true,&quot;335559738&quot;:120}\">\u00a0<\/span><\/li><\/ul><div>\u00a0<\/div><ol start=\"3\"><li><b><span data-contrast=\"auto\"> Pr\u00e9voyance et s\u00e9curit\u00e9 sociale<\/span><\/b><\/li><\/ol><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Si vous travaillez, vous serez automatiquement affili\u00e9 \u00e0 l\u2019<\/span><b><span data-contrast=\"auto\">AVS (1er pilier)<\/span><\/b><span data-contrast=\"auto\"> et probablement au <\/span><b><span data-contrast=\"auto\">2e pilier (LPP)<\/span><\/b><span data-contrast=\"auto\"> automatiquement via votre employeur.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"3\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Vous pouvez aussi ouvrir un <\/span><b><span data-contrast=\"auto\">3e pilier<\/span><\/b><span data-contrast=\"auto\"> pour \u00e9pargner de mani\u00e8re priv\u00e9e, tout en b\u00e9n\u00e9ficiant d\u2019avantages fiscaux.<\/span>\u00a0<br \/><span data-contrast=\"auto\">\u25a1<\/span><span data-contrast=\"auto\"> Ce point demande une <\/span><a href=\"https:\/\/tally.so\/r\/w4D2Xb\"><span data-contrast=\"none\"><span style=\"text-decoration: underline;\">\u00e9valuation de votre situation personnelle<\/span><\/span><\/a><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><ol start=\"4\"><li><b><span data-contrast=\"auto\"> Ouvrir un compte bancaire en Suisse<\/span><\/b><\/li><\/ol><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"4\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Essentiel pour recevoir votre salaire et r\u00e9gler vos payements.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><p><span data-contrast=\"auto\">Avec permis B = Neon<\/span>\u00a0<br \/><span data-contrast=\"auto\">Sans Permis B = <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.yuh.com\/download\">Yuh<\/a><\/span><span data-contrast=\"auto\"> (pour aider le projet merci d\u2019utiliser le code d\u2019invitation\u202f: fqzhn5)<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><ol start=\"5\"><li><b><span data-contrast=\"auto\"> Fiscalit\u00e9<\/span><\/b><\/li><\/ol><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">En fonction de votre permis et situation, vous serez soumis \u00e0 <\/span><b><span data-contrast=\"auto\">l\u2019imp\u00f4t \u00e0 la source<\/span><\/b><span data-contrast=\"auto\"> ou \u00e0 <\/span><b><span data-contrast=\"auto\">une d\u00e9claration d\u2019imp\u00f4t annuelle<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"5\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Une bonne <\/span><a href=\"https:\/\/preview.cashflowch.com\/simulation-declaration-dimpots\"><span data-contrast=\"none\"><span style=\"text-decoration: underline;\">planification fiscale<\/span><\/span><\/a><span data-contrast=\"auto\"> d\u00e8s le d\u00e9part permet d\u2019<\/span><b><span data-contrast=\"auto\">\u00e9viter des erreurs co\u00fbteuses<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><ol start=\"6\"><li><b><span data-contrast=\"auto\"> Assurances choses (RC, m\u00e9nage, voiture, etc.)<\/span><\/b><\/li><\/ol><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"6\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Pensez \u00e0 souscrire une <\/span><span style=\"text-decoration: underline;\"><b><a href=\"https:\/\/tally.so\/r\/mD5beq\">responsabilit\u00e9 civile priv\u00e9e <\/a><\/b><\/span><span data-contrast=\"auto\">(importante pour une recherche d\u2019appartement), une assurance <\/span><b><span data-contrast=\"auto\">m\u00e9nage<\/span><\/b><span data-contrast=\"auto\">, ou encore une <\/span><b><span data-contrast=\"auto\"><a href=\"https:\/\/tally.so\/r\/wQ57B1\"><span style=\"text-decoration: underline;\">assurance v\u00e9hicule<\/span><\/a><\/span><\/b><span data-contrast=\"auto\"> si vous en poss\u00e9dez un.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><h2><b><span data-contrast=\"auto\">VOUS QUITTEZ LA SUISSE ? VOICI CE QU\u2019IL FAUT PR\u00c9VOIR :<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/h2><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><ol><li><b><span data-contrast=\"auto\"> Annoncer votre d\u00e9part<\/span><\/b><\/li><\/ol><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Vous devez <\/span><b><span data-contrast=\"auto\">vous d\u00e9sinscrire aupr\u00e8s de votre commune <\/span><\/b><span data-contrast=\"auto\">(contr\u00f4le des habitants) avant de quitter le pays.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"7\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Indiquez votre nouvelle adresse \u00e0 l\u2019\u00e9tranger.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><ol start=\"2\"><li><b><span data-contrast=\"auto\"> Cl\u00f4turer ou transf\u00e9rer vos assurances et abonnements<\/span><\/b><\/li><\/ol><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"8\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">R\u00e9siliez votre <\/span><b><span data-contrast=\"auto\">assurance maladie obligatoire<\/span><\/b><span data-contrast=\"auto\"> (<a href=\"https:\/\/tally.so\/r\/3EXAWN\"><span style=\"text-decoration: underline;\">LAMal<\/span><\/a>), en fournissant une preuve de d\u00e9part ou d\u2019affiliation dans le nouveau pays.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"8\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Informez vos assureurs (voiture, m\u00e9nage, RC, etc.) pour <\/span><b><span data-contrast=\"auto\">\u00e9viter des primes inutiles<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><ol start=\"3\"><li><b><span data-contrast=\"auto\"> R\u00e9gulariser votre situation fiscale<\/span><\/b><\/li><\/ol><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"9\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">Une <\/span><b><span data-contrast=\"auto\">d\u00e9claration fiscale de d\u00e9part<\/span><\/b><span data-contrast=\"auto\"> doit \u00eatre d\u00e9pos\u00e9e (taxation jusqu\u2019\u00e0 le jour de d\u00e9part).<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"9\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">En cas de retrait de votre 2e ou 3e pilier, <\/span><b><span data-contrast=\"auto\">des imp\u00f4ts sp\u00e9ciaux<\/span><\/b><span data-contrast=\"auto\"> peuvent s\u2019appliquer. <\/span><span data-contrast=\"auto\">Il est essentiel d\u2019<\/span><b><span data-contrast=\"auto\">anticiper cela avec un conseiller<\/span><\/b><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><ol start=\"4\"><li><b><span data-contrast=\"auto\"> G\u00e9rer vos avoirs de pr\u00e9voyance<\/span><\/b><\/li><\/ol><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"10\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">1er pilier (AVS)<\/span><\/b><span data-contrast=\"auto\"> : les cotisations cessent, mais peuvent parfois \u00eatre transf\u00e9r\u00e9es selon les conventions internationales ou selon la situation vous pourriez opter pour continuer avec des <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/preview.cashflowch.com\/cotisation-facultative-1er-pilier\">cotisations facultatives<\/a><\/span><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"10\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">2e pilier (LPP)<\/span><\/b><span data-contrast=\"auto\"> : possibilit\u00e9 de transf\u00e9rer vers une institution de libre passage ou, dans certains cas, de retirer l\u2019avoir.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"10\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><b><span data-contrast=\"auto\">3e pilier<\/span><\/b><span data-contrast=\"auto\"> : peut parfois \u00eatre retir\u00e9, mais sous conditions (d\u00e9part d\u00e9finitif, retraite, etc.).<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><p><a style=\"background-color: #ffffff;\" href=\"http:\/\/link r\u00e9servation calendrier : https:\/\/calendar.notion.so\/meet\/davidecasellini\/people\"><span data-contrast=\"auto\">&#8211;&gt; <span style=\"text-decoration: underline;\">Une \u00e9valuation de votre situation permet de trouver les meilleures solutions pour vous\u202f!<\/span><\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/a><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><ol start=\"5\"><li><b><span data-contrast=\"auto\"> Cl\u00f4ture ou gestion de vos comptes bancaires et patrimoine<\/span><\/b><\/li><\/ol><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"11\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"auto\">\u00c9vitez de laisser des comptes inactifs ou non d\u00e9clar\u00e9s.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><ul><li data-leveltext=\"\uf0b7\" data-font=\"Symbol\" data-listid=\"11\" data-list-defn-props=\"{&quot;335552541&quot;:1,&quot;335559685&quot;:720,&quot;335559991&quot;:360,&quot;469769226&quot;:&quot;Symbol&quot;,&quot;469769242&quot;:[8226],&quot;469777803&quot;:&quot;left&quot;,&quot;469777804&quot;:&quot;\uf0b7&quot;,&quot;469777815&quot;:&quot;multilevel&quot;}\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"auto\">Pensez \u00e0 <\/span><b><span data-contrast=\"auto\">revoir votre strat\u00e9gie patrimoniale<\/span><\/b><span data-contrast=\"auto\"> en fonction de votre nouveau pays de r\u00e9sidence et votre politique de placement.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/li><\/ul><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p><h2><b><span data-contrast=\"auto\">Cash-Flow CH vous accompagne dans chaque \u00e9tape<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/h2><div><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/div><div><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/div><h5><span data-contrast=\"auto\">Nous vous aidons \u00e0 :<\/span>\u00a0<\/h5><p><span data-contrast=\"auto\">\u2714<\/span><span data-contrast=\"auto\">\ufe0f<\/span> <b><span data-contrast=\"auto\">Planifier votre arriv\u00e9e ou votre d\u00e9part<\/span><\/b><span data-contrast=\"auto\"> d\u2019un point de vue administratif et financier<\/span>\u00a0<br \/><span data-contrast=\"auto\">\u2714<\/span><span data-contrast=\"auto\">\ufe0f<\/span><span data-contrast=\"auto\"> Optimiser votre <\/span><b><span data-contrast=\"auto\">fiscalit\u00e9, votre pr\u00e9voyance et vos assurances<\/span><\/b>\u00a0<br \/><span data-contrast=\"auto\">\u2714<\/span><span data-contrast=\"auto\">\ufe0f<\/span><span data-contrast=\"auto\"> Prot\u00e9ger et organiser votre <\/span><b><span data-contrast=\"auto\">patrimoine priv\u00e9 et professionnel<\/span><\/b>\u00a0<br \/><span data-contrast=\"auto\">\u2714<\/span><span data-contrast=\"auto\">\ufe0f<\/span><span data-contrast=\"auto\"> Mettre en place une <\/span><b><span data-contrast=\"auto\">strat\u00e9gie adapt\u00e9e \u00e0 votre nouveau contexte de vie<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">\ud83d\udcc5<\/span><span data-contrast=\"auto\"> Prenez rendez-vous pour une analyse personnalis\u00e9e<\/span>\u00a0<br \/><span data-contrast=\"auto\">\ud83d\udc49<\/span> <a href=\"https:\/\/cashflowch.com\/en\/\"><span data-contrast=\"none\"><span style=\"text-decoration: underline;\">www.cashflowch.com<\/span><\/span><\/a><span data-contrast=\"auto\"> \u2013 <\/span><i><span data-contrast=\"auto\">Comprendre. <\/span><\/i><i><span data-contrast=\"auto\">Planifier. D\u00e9cider.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true}\">\u00a0<\/span><\/p><p><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2aa95cc1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no elementor-invisible\" data-id=\"2aa95cc1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f05c932\" data-id=\"1f05c932\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65974571 elementor-widget elementor-widget-heading\" data-id=\"65974571\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">R\u00c9SERVEZ VOTRE CONSULTATION FINANCI\u00c8RE<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79bd31f9 elementor-widget elementor-widget-heading\" data-id=\"79bd31f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">AVEC CASH-FLOW CH<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60d8328 elementor-widget elementor-widget-spacer\" data-id=\"60d8328\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9219e0 elementor-invisible elementor-widget elementor-widget-button\" data-id=\"9219e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/calendar.notion.so\/meet\/davidecasellini\/people\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9servez un rendez-vous informatif<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Arriv\u00e9e ou d\u00e9part de la Suisse Conseils personnalis\u00e9s, gestion rigoureuse et solutions adapt\u00e9es pour faciliter votre arriv\u00e9e ou votre d\u00e9part de la Suisse en toute s\u00e9r\u00e9nit\u00e9. R\u00e9servez un rendez-vous informatif Arriv\u00e9e ou d\u00e9part de la Suisse\u200b S\u2019installer en Suisse ou quitter le pays demande bien plus que de faire ses valises. Chez Cash-Flow CH, nous accompagnons nos clients dans toutes les \u00e9tapes administratives, fiscales, sociales et patrimoniales pour que chaque transition se fasse en toute s\u00e9r\u00e9nit\u00e9.\u00a0 \u00a0 \u00a0 VOUS ARRIVEZ EN SUISSE ? VOICI LES \u00c9TAPES \u00c0 SUIVRE :\u00a0 \u00a0\u00a0 Annoncer votre arriv\u00e9e Vous devez vous enregistrer aupr\u00e8s de la commune de domicile dans les 14 jours suivant votre arriv\u00e9e.\u00a0 Pour les ressortissants \u00e9trangers : demande de permis de s\u00e9jour (L, B, C selon votre situation).\u00a0 \u00a0 Assurer votre couverture sant\u00e9 (obligatoire) L\u2019assurance maladie de base (LAMal) est obligatoire dans les 3 mois suivant l\u2019arriv\u00e9e. (si le d\u00e9lai n\u2019est pas respect\u00e9, il y a des sanctions).\u00a0 Il est possible de comparer les primes selon votre canton de domicile, compagnie d\u2019assurance, mod\u00e8le et franchise.\u00a0selon la situation financi\u00e8re, il est possible de demander des aides directement au canton de domicile (liste).\u00a0\u25a1 Dans le cadre des Subventions de prime d\u2019assurance maladie (Remboursement individuel de prime RIP), nous tenons \u00e0 pr\u00e9ciser que nous ne faisons pas de d\u00e9marchage pour l&rsquo;octroi d\u2019aides financi\u00e8res et n&rsquo;organisons aucun rendez-vous\u00a0 Une assurance compl\u00e9mentaire peut \u00eatre utile pour une meilleure prise en charge et couvrir les frais que la couverture obligatoire ne couvre pas.\u00a0\u00a0 \u00a0 Pr\u00e9voyance et s\u00e9curit\u00e9 sociale Si vous travaillez, vous serez automatiquement affili\u00e9 \u00e0 l\u2019AVS (1er pilier) et probablement au 2e pilier (LPP) automatiquement via votre employeur.\u00a0 Vous pouvez aussi ouvrir un 3e pilier pour \u00e9pargner de mani\u00e8re priv\u00e9e, tout en b\u00e9n\u00e9ficiant d\u2019avantages fiscaux.\u00a0\u25a1 Ce point demande une \u00e9valuation de votre situation personnelle.\u00a0 \u00a0 Ouvrir un compte bancaire en Suisse Essentiel pour recevoir votre salaire et r\u00e9gler vos payements.\u00a0 Avec permis B = Neon\u00a0Sans Permis B = Yuh (pour aider le projet merci d\u2019utiliser le code d\u2019invitation\u202f: fqzhn5)\u00a0 \u00a0 Fiscalit\u00e9 En fonction de votre permis et situation, vous serez soumis \u00e0 l\u2019imp\u00f4t \u00e0 la source ou \u00e0 une d\u00e9claration d\u2019imp\u00f4t annuelle.\u00a0 Une bonne planification fiscale d\u00e8s le d\u00e9part permet d\u2019\u00e9viter des erreurs co\u00fbteuses.\u00a0 \u00a0 Assurances choses (RC, m\u00e9nage, voiture, etc.) Pensez \u00e0 souscrire une responsabilit\u00e9 civile priv\u00e9e (importante pour une recherche d\u2019appartement), une assurance m\u00e9nage, ou encore une assurance v\u00e9hicule si vous en poss\u00e9dez un.\u00a0 \u00a0 \u00a0 \u00a0 VOUS QUITTEZ LA SUISSE ? VOICI CE QU\u2019IL FAUT PR\u00c9VOIR :\u00a0 \u00a0 Annoncer votre d\u00e9part Vous devez vous d\u00e9sinscrire aupr\u00e8s de votre commune (contr\u00f4le des habitants) avant de quitter le pays.\u00a0 Indiquez votre nouvelle adresse \u00e0 l\u2019\u00e9tranger.\u00a0 \u00a0 \u00a0 Cl\u00f4turer ou transf\u00e9rer vos assurances et abonnements R\u00e9siliez votre assurance maladie obligatoire (LAMal), en fournissant une preuve de d\u00e9part ou d\u2019affiliation dans le nouveau pays.\u00a0 Informez vos assureurs (voiture, m\u00e9nage, RC, etc.) pour \u00e9viter des primes inutiles.\u00a0 \u00a0 \u00a0 R\u00e9gulariser votre situation fiscale Une d\u00e9claration fiscale de d\u00e9part doit \u00eatre d\u00e9pos\u00e9e (taxation jusqu\u2019\u00e0 le jour de d\u00e9part).\u00a0 En cas de retrait de votre 2e ou 3e pilier, des imp\u00f4ts sp\u00e9ciaux peuvent s\u2019appliquer. Il est essentiel d\u2019anticiper cela avec un conseiller.\u00a0 \u00a0 \u00a0 G\u00e9rer vos avoirs de pr\u00e9voyance 1er pilier (AVS) : les cotisations cessent, mais peuvent parfois \u00eatre transf\u00e9r\u00e9es selon les conventions internationales ou selon la situation vous pourriez opter pour continuer avec des cotisations facultatives.\u00a0 2e pilier (LPP) : possibilit\u00e9 de transf\u00e9rer vers une institution de libre passage ou, dans certains cas, de retirer l\u2019avoir.\u00a0 3e pilier : peut parfois \u00eatre retir\u00e9, mais sous conditions (d\u00e9part d\u00e9finitif, retraite, etc.).\u00a0 &#8211;&gt; Une \u00e9valuation de votre situation permet de trouver les meilleures solutions pour vous\u202f!\u00a0 \u00a0 \u00a0 Cl\u00f4ture ou gestion de vos comptes bancaires et patrimoine \u00c9vitez de laisser des comptes inactifs ou non d\u00e9clar\u00e9s.\u00a0 Pensez \u00e0 revoir votre strat\u00e9gie patrimoniale en fonction de votre nouveau pays de r\u00e9sidence et votre politique de placement.\u00a0 \u00a0 \u00a0 \u00a0 Cash-Flow CH vous accompagne dans chaque \u00e9tape\u00a0 \u00a0\u00a0 Nous vous aidons \u00e0 :\u00a0 \u2714\ufe0f Planifier votre arriv\u00e9e ou votre d\u00e9part d\u2019un point de vue administratif et financier\u00a0\u2714\ufe0f Optimiser votre fiscalit\u00e9, votre pr\u00e9voyance et vos assurances\u00a0\u2714\ufe0f Prot\u00e9ger et organiser votre patrimoine priv\u00e9 et professionnel\u00a0\u2714\ufe0f Mettre en place une strat\u00e9gie adapt\u00e9e \u00e0 votre nouveau contexte de vie\u00a0 \ud83d\udcc5 Prenez rendez-vous pour une analyse personnalis\u00e9e\u00a0\ud83d\udc49 www.cashflowch.com \u2013 Comprendre. Planifier. D\u00e9cider.\u00a0 \u00a0 \u00a0 \u00a0 R\u00c9SERVEZ VOTRE CONSULTATION FINANCI\u00c8RE AVEC CASH-FLOW CH R\u00e9servez un rendez-vous informatif<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-1358","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cashflowch.com\/en\/wp-json\/wp\/v2\/pages\/1358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cashflowch.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cashflowch.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cashflowch.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cashflowch.com\/en\/wp-json\/wp\/v2\/comments?post=1358"}],"version-history":[{"count":43,"href":"https:\/\/cashflowch.com\/en\/wp-json\/wp\/v2\/pages\/1358\/revisions"}],"predecessor-version":[{"id":2566,"href":"https:\/\/cashflowch.com\/en\/wp-json\/wp\/v2\/pages\/1358\/revisions\/2566"}],"wp:attachment":[{"href":"https:\/\/cashflowch.com\/en\/wp-json\/wp\/v2\/media?parent=1358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}